{"id":2,"date":"2018-12-06T10:09:19","date_gmt":"2018-12-06T13:09:19","guid":{"rendered":"https:\/\/jclatina.com.ar\/?page_id=2"},"modified":"2025-10-09T16:51:00","modified_gmt":"2025-10-09T19:51:00","slug":"la-empresa","status":"publish","type":"page","link":"https:\/\/jclatina.com.ar\/index.php\/la-empresa\/","title":{"rendered":"La Empresa"},"content":{"rendered":"<h2>Bienvenidos a JC Latina S.A.S!<\/h2>\n<p>JC LATINA S.A.S es una empresa cordobesa que ha sido concebida para atender los negocios de los empresarios del campo, quienes requieren innumerables operaciones de \u00edndole financiero.<\/p>\n<p>De estas relaciones generadas, y de la necesidad puntual de cada persona que conf\u00eda en MIC, surgen nuevas y excelentes oportunidades de negocios e inversiones, logrando de esta manera, afianzar los v\u00ednculos con nuestros clientes.<\/p>\n<p>MIC cuenta con altos est\u00e1ndares de calidad y servicio en la atenci\u00f3n a todos nuestros clientes, gracias a la capacidad profesional y personal de sus recursos humanos, la seriedad y responsabilidad en el trabajo, el<br \/>\nrespeto hacia nuestros clientes y la visi\u00f3n hacia donde nos dirigimos y hasta donde queremos llegar.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"slide-text-bg2\"><span>Bienvenidos a JC Latina S.A.S! JC LATINA S.A.S es una empresa cordobesa que ha sido concebida para atender los negocios de los empresarios del campo, quien<\/span><\/div>\n<div class=\"slide-btn-area-sm\"><a href=\"https:\/\/jclatina.com.ar\/index.php\/la-empresa\/\" class=\"slide-btn-sm\">Read More<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/jclatina.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jclatina.com.ar\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jclatina.com.ar\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jclatina.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jclatina.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":7,"href":"https:\/\/jclatina.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":747,"href":"https:\/\/jclatina.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/2\/revisions\/747"}],"wp:attachment":[{"href":"https:\/\/jclatina.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}